{"id":15832,"date":"2026-04-03T10:56:28","date_gmt":"2026-04-03T08:56:28","guid":{"rendered":"https:\/\/heldersebinnenstad.nl\/?p=15832"},"modified":"2026-04-03T10:56:28","modified_gmt":"2026-04-03T08:56:28","slug":"nieuwe-zomerexpositie-op-lichtschip-texel","status":"publish","type":"post","link":"https:\/\/heldersebinnenstad.nl\/de\/nieuwe-zomerexpositie-op-lichtschip-texel\/","title":{"rendered":"Nieuwe zomerexpositie op Lichtschip Texel"},"content":{"rendered":"<p>DEN HELDER \u2013 Met het luiden van de scheepsbel op het dek van het lichtschip Texel is op woensdagmiddag 1 april de nieuwe zomerexpositie, getiteld \u2018De mensen achter het licht\u2019, officieel geopend. De openingshandeling is verricht door directeur Erik Bekkering van Citymarketing Den Helder en voorzitter Sjaak Vrieling voorzitter van de Stichting Historie der Kustverlichting, de eigenaar en exploitant van het lichtschip.<\/p>\n<p>De nieuwe zomerexpositie is een eerbetoon aan de bemanningen van de lichtschepen die jarenlang de scheepvaartroutes voor onze kust hebben beveiligd. Deze drijvende vuurtorens hebben tot in de jaren negentig van de vorige eeuw\u00a0 voor de Nederlandse kust permanent als vaste bakens in zee dienst gedaan. Zo ook het lichtschip Texel van 1952 tot 1992. Eerst bemand door een ploeg van 10 tot 12 mensen die om te twee weken werden afgelost en na de automatisering in 1976 geheel onbemand.<\/p>\n<p>Volgens voorzitter Sjaak Vrieling is de expositie opgezet om de herinneringen aan de lichtschepen en hun bemanningen levend te houden. \u201cJe leert op de expositie meer over het werken aan boord, de hierbij door de bemanningen getoonde inzet en hun rol tijdens de levensloop van de lichtschepen. Verder luidt de opening gelijk ook de start van het museumseizoen 2026 in\u201d. Voor de pas tot directeur benoemde Erik Bekkering is deze offici\u00eble \u00a0openingshandeling \u00e9\u00e9n van zijn eerste publieke optredens. Hij noemt Den Helder de stad van het licht. \u201cHet waren niet alleen de mensen op deze schepen die zorgden voor het licht, maar ook de inwoners van deze stad. Mensen die koers wisten te houden. De expositie geeft de betekenis van deze mensen weer en zet ze centraal neer.\u201d<\/p>\n<p>Het lichtschip Texel maakt in Den Helder al meer dan dertig jaar deel uit van de collectie museale schepen van Museumhaven Willemsoord. Al die tijd wordt het opvallend roodgekleurde schip in een tiptop conditie gehouden door een groep enthousiaste vrijwilligers, die ook altijd bereid zijn om de bezoekers tekst en uitleg te geven over hun bijzondere schip en het\u00a0 leven en werken aan boord.<\/p>\n<p>Foto: Sjaak Vrieling en Erik Bekkering (rechts) \u00a0hebben met het luiden van de scheepsbel de expositie officieel geopend. (foto: Paul Schaap)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>DEN HELDER \u2013 Met het luiden van de scheepsbel op het dek van het lichtschip Texel is op woensdagmiddag 1 april de nieuwe zomerexpositie, getiteld \u2018De mensen achter het licht\u2019, officieel geopend. De openingshandeling is verricht door directeur Erik Bekkering van Citymarketing Den Helder en voorzitter Sjaak Vrieling voorzitter van de Stichting Historie der Kustverlichting, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":15833,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-15832","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nieuwe zomerexpositie op Lichtschip Texel - Helderse binnenstad<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/heldersebinnenstad.nl\/nieuwe-zomerexpositie-op-lichtschip-texel\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nieuwe zomerexpositie op Lichtschip Texel - Helderse binnenstad\" \/>\n<meta property=\"og:description\" content=\"DEN HELDER \u2013 Met het luiden van de scheepsbel op het dek van het lichtschip Texel is op woensdagmiddag 1 april de nieuwe zomerexpositie, getiteld \u2018De mensen achter het licht\u2019, officieel geopend. De openingshandeling is verricht door directeur Erik Bekkering van Citymarketing Den Helder en voorzitter Sjaak Vrieling voorzitter van de Stichting Historie der Kustverlichting, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/heldersebinnenstad.nl\/nieuwe-zomerexpositie-op-lichtschip-texel\/\" \/>\n<meta property=\"og:site_name\" content=\"Helderse binnenstad\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/nl-nl.facebook.com\/heldersebinnenstad\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-03T08:56:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/heldersebinnenstad.nl\/wp-content\/uploads\/2026\/04\/Opening-zomerexpositie-lichtschip-Foto-Paul-Schaap_1280x853.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Fred van Eck\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fred van Eck\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/heldersebinnenstad.nl\\\/nieuwe-zomerexpositie-op-lichtschip-texel\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/heldersebinnenstad.nl\\\/nieuwe-zomerexpositie-op-lichtschip-texel\\\/\"},\"author\":{\"name\":\"Fred van Eck\",\"@id\":\"https:\\\/\\\/heldersebinnenstad.nl\\\/#\\\/schema\\\/person\\\/b7420807adb0ee30866ad1c97cdbd5c0\"},\"headline\":\"Nieuwe zomerexpositie op Lichtschip Texel\",\"datePublished\":\"2026-04-03T08:56:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/heldersebinnenstad.nl\\\/nieuwe-zomerexpositie-op-lichtschip-texel\\\/\"},\"wordCount\":353,\"image\":{\"@id\":\"https:\\\/\\\/heldersebinnenstad.nl\\\/nieuwe-zomerexpositie-op-lichtschip-texel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/heldersebinnenstad.nl\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Opening-zomerexpositie-lichtschip-Foto-Paul-Schaap_1280x853.jpg\",\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/heldersebinnenstad.nl\\\/nieuwe-zomerexpositie-op-lichtschip-texel\\\/\",\"url\":\"https:\\\/\\\/heldersebinnenstad.nl\\\/nieuwe-zomerexpositie-op-lichtschip-texel\\\/\",\"name\":\"Nieuwe zomerexpositie op Lichtschip Texel - Helderse binnenstad\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/heldersebinnenstad.nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/heldersebinnenstad.nl\\\/nieuwe-zomerexpositie-op-lichtschip-texel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/heldersebinnenstad.nl\\\/nieuwe-zomerexpositie-op-lichtschip-texel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/heldersebinnenstad.nl\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Opening-zomerexpositie-lichtschip-Foto-Paul-Schaap_1280x853.jpg\",\"datePublished\":\"2026-04-03T08:56:28+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/heldersebinnenstad.nl\\\/#\\\/schema\\\/person\\\/b7420807adb0ee30866ad1c97cdbd5c0\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/heldersebinnenstad.nl\\\/nieuwe-zomerexpositie-op-lichtschip-texel\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/heldersebinnenstad.nl\\\/nieuwe-zomerexpositie-op-lichtschip-texel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/heldersebinnenstad.nl\\\/nieuwe-zomerexpositie-op-lichtschip-texel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/heldersebinnenstad.nl\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Opening-zomerexpositie-lichtschip-Foto-Paul-Schaap_1280x853.jpg\",\"contentUrl\":\"https:\\\/\\\/heldersebinnenstad.nl\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Opening-zomerexpositie-lichtschip-Foto-Paul-Schaap_1280x853.jpg\",\"width\":1280,\"height\":853},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/heldersebinnenstad.nl\\\/nieuwe-zomerexpositie-op-lichtschip-texel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/heldersebinnenstad.nl\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nieuwe zomerexpositie op Lichtschip Texel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/heldersebinnenstad.nl\\\/#website\",\"url\":\"https:\\\/\\\/heldersebinnenstad.nl\\\/\",\"name\":\"Helderse binnenstad\",\"description\":\"Op deze website kunt u informatie nalezen die het voor u eenvoudiger maakt om iets op te zoeken in de Helderse binnenstad.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/heldersebinnenstad.nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/heldersebinnenstad.nl\\\/#\\\/schema\\\/person\\\/b7420807adb0ee30866ad1c97cdbd5c0\",\"name\":\"Fred van Eck\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nieuwe zomerexpositie op Lichtschip Texel - Helderse binnenstad","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/heldersebinnenstad.nl\/nieuwe-zomerexpositie-op-lichtschip-texel\/","og_locale":"de_DE","og_type":"article","og_title":"Nieuwe zomerexpositie op Lichtschip Texel - Helderse binnenstad","og_description":"DEN HELDER \u2013 Met het luiden van de scheepsbel op het dek van het lichtschip Texel is op woensdagmiddag 1 april de nieuwe zomerexpositie, getiteld \u2018De mensen achter het licht\u2019, officieel geopend. De openingshandeling is verricht door directeur Erik Bekkering van Citymarketing Den Helder en voorzitter Sjaak Vrieling voorzitter van de Stichting Historie der Kustverlichting, [&hellip;]","og_url":"https:\/\/heldersebinnenstad.nl\/nieuwe-zomerexpositie-op-lichtschip-texel\/","og_site_name":"Helderse binnenstad","article_publisher":"https:\/\/nl-nl.facebook.com\/heldersebinnenstad","article_published_time":"2026-04-03T08:56:28+00:00","og_image":[{"width":1280,"height":853,"url":"https:\/\/heldersebinnenstad.nl\/wp-content\/uploads\/2026\/04\/Opening-zomerexpositie-lichtschip-Foto-Paul-Schaap_1280x853.jpg","type":"image\/jpeg"}],"author":"Fred van Eck","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Fred van Eck","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/heldersebinnenstad.nl\/nieuwe-zomerexpositie-op-lichtschip-texel\/#article","isPartOf":{"@id":"https:\/\/heldersebinnenstad.nl\/nieuwe-zomerexpositie-op-lichtschip-texel\/"},"author":{"name":"Fred van Eck","@id":"https:\/\/heldersebinnenstad.nl\/#\/schema\/person\/b7420807adb0ee30866ad1c97cdbd5c0"},"headline":"Nieuwe zomerexpositie op Lichtschip Texel","datePublished":"2026-04-03T08:56:28+00:00","mainEntityOfPage":{"@id":"https:\/\/heldersebinnenstad.nl\/nieuwe-zomerexpositie-op-lichtschip-texel\/"},"wordCount":353,"image":{"@id":"https:\/\/heldersebinnenstad.nl\/nieuwe-zomerexpositie-op-lichtschip-texel\/#primaryimage"},"thumbnailUrl":"https:\/\/heldersebinnenstad.nl\/wp-content\/uploads\/2026\/04\/Opening-zomerexpositie-lichtschip-Foto-Paul-Schaap_1280x853.jpg","inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/heldersebinnenstad.nl\/nieuwe-zomerexpositie-op-lichtschip-texel\/","url":"https:\/\/heldersebinnenstad.nl\/nieuwe-zomerexpositie-op-lichtschip-texel\/","name":"Nieuwe zomerexpositie op Lichtschip Texel - Helderse binnenstad","isPartOf":{"@id":"https:\/\/heldersebinnenstad.nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/heldersebinnenstad.nl\/nieuwe-zomerexpositie-op-lichtschip-texel\/#primaryimage"},"image":{"@id":"https:\/\/heldersebinnenstad.nl\/nieuwe-zomerexpositie-op-lichtschip-texel\/#primaryimage"},"thumbnailUrl":"https:\/\/heldersebinnenstad.nl\/wp-content\/uploads\/2026\/04\/Opening-zomerexpositie-lichtschip-Foto-Paul-Schaap_1280x853.jpg","datePublished":"2026-04-03T08:56:28+00:00","author":{"@id":"https:\/\/heldersebinnenstad.nl\/#\/schema\/person\/b7420807adb0ee30866ad1c97cdbd5c0"},"breadcrumb":{"@id":"https:\/\/heldersebinnenstad.nl\/nieuwe-zomerexpositie-op-lichtschip-texel\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/heldersebinnenstad.nl\/nieuwe-zomerexpositie-op-lichtschip-texel\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/heldersebinnenstad.nl\/nieuwe-zomerexpositie-op-lichtschip-texel\/#primaryimage","url":"https:\/\/heldersebinnenstad.nl\/wp-content\/uploads\/2026\/04\/Opening-zomerexpositie-lichtschip-Foto-Paul-Schaap_1280x853.jpg","contentUrl":"https:\/\/heldersebinnenstad.nl\/wp-content\/uploads\/2026\/04\/Opening-zomerexpositie-lichtschip-Foto-Paul-Schaap_1280x853.jpg","width":1280,"height":853},{"@type":"BreadcrumbList","@id":"https:\/\/heldersebinnenstad.nl\/nieuwe-zomerexpositie-op-lichtschip-texel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/heldersebinnenstad.nl\/de\/"},{"@type":"ListItem","position":2,"name":"Nieuwe zomerexpositie op Lichtschip Texel"}]},{"@type":"WebSite","@id":"https:\/\/heldersebinnenstad.nl\/#website","url":"https:\/\/heldersebinnenstad.nl\/","name":"Helderse binnenstad","description":"Op deze website kunt u informatie nalezen die het voor u eenvoudiger maakt om iets op te zoeken in de Helderse binnenstad.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/heldersebinnenstad.nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/heldersebinnenstad.nl\/#\/schema\/person\/b7420807adb0ee30866ad1c97cdbd5c0","name":"Fred van Eck"}]}},"_links":{"self":[{"href":"https:\/\/heldersebinnenstad.nl\/de\/wp-json\/wp\/v2\/posts\/15832","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/heldersebinnenstad.nl\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/heldersebinnenstad.nl\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/heldersebinnenstad.nl\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/heldersebinnenstad.nl\/de\/wp-json\/wp\/v2\/comments?post=15832"}],"version-history":[{"count":1,"href":"https:\/\/heldersebinnenstad.nl\/de\/wp-json\/wp\/v2\/posts\/15832\/revisions"}],"predecessor-version":[{"id":15836,"href":"https:\/\/heldersebinnenstad.nl\/de\/wp-json\/wp\/v2\/posts\/15832\/revisions\/15836"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/heldersebinnenstad.nl\/de\/wp-json\/wp\/v2\/media\/15833"}],"wp:attachment":[{"href":"https:\/\/heldersebinnenstad.nl\/de\/wp-json\/wp\/v2\/media?parent=15832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}